{"id":3286,"date":"2024-03-25T13:43:04","date_gmt":"2024-03-25T13:43:04","guid":{"rendered":"https:\/\/www.comec-italy.com\/privacy-policy\/"},"modified":"2024-03-26T08:13:39","modified_gmt":"2024-03-26T08:13:39","slug":"privacy-policy","status":"publish","type":"page","link":"https:\/\/www.comec-italy.com\/pt-pt\/privacy-policy\/","title":{"rendered":"Privacy policy"},"content":{"rendered":"<!--googleoff: all-->\n<p><strong>Informa&ccedil;&atilde;o sobre o tratamento dos Dados Pessoais recolhidos atrav&eacute;s deste s&iacute;tio Web<\/strong><br> <\/p>\n\n\n<p><strong>1. Introdu&ccedil;&atilde;o e refer&ecirc;ncias normativas<\/strong><br> A presente informa&ccedil;&atilde;o descreve o tratamento dos dados pessoais recolhidos atrav&eacute;s deste s&iacute;tio Web, incluindo os obtidos mediante cookies, tecnologias de rastreio e &mdash; quando existentes &mdash; formul&aacute;rios de contacto e as demais funcionalidades eventualmente ativas no s&iacute;tio.<br> A presente informa&ccedil;&atilde;o dirige-se a qualquer pessoa que aceda ou utilize este s&iacute;tio, descrevendo as formas de recolha, utiliza&ccedil;&atilde;o e prote&ccedil;&atilde;o dos dados pessoais do utilizador, bem como os direitos reconhecidos por lei.<br> As presentes disposi&ccedil;&otilde;es n&atilde;o dizem respeito a outros s&iacute;tios, p&aacute;ginas ou servi&ccedil;os em linha acess&iacute;veis atrav&eacute;s de liga&ccedil;&otilde;es externas eventualmente presentes no s&iacute;tio, relativamente aos quais se recomenda a consulta das respetivas pol&iacute;ticas de privacidade.<br> A presente informa&ccedil;&atilde;o &eacute; prestada em cumprimento das principais normas nacionais e internacionais em mat&eacute;ria de prote&ccedil;&atilde;o de dados pessoais, entre as quais:<\/p>\n<ul>\n<li class=\"map_gdpr_text\">Regulamento (UE) 2016\/679 (RGPD) e Diretiva 2002\/58\/CE, denominada Diretiva ePrivacy<\/li>\n\n\n\n\n\n\n\n\n\n\n\n\n\n\n\n\n\n\n\n\n\n\n\n\n\n\n\n\n\n<li>Outras normas eventualmente aplic&aacute;veis.<\/li>\n<\/ul>\n\n\n<p><strong>2. Quem gere os seus dados e como pode contactar-nos?<\/strong><br> Os seus dados pessoais s&atilde;o tratados por:<br> <span class=\"map_identity_name\">COMEC SRL<br><\/span> <span class=\"map_identity_address\">Via Copernico n.58\/60 \u2013 36034 Malo (VI)<br><\/span> <span class=\"map_identity_email\">info@comec-italy.com<br><\/span> <span class=\"map_identity_vat_id\">ID de IVA: IT01306870245<\/span><\/p>\n\n\n\n<p class=\"map_dpo_text_unset\">Para qualquer informa&ccedil;&atilde;o relativa ao tratamento dos dados pessoais ou para exercer os direitos previstos na lei, os titulares dos dados podem contactar o Respons&aacute;vel pelo tratamento.<\/p>\n\n\n<p><strong>3. Com base em que fundamentos jur&iacute;dicos tratamos os seus dados?<\/strong><br> O tratamento dos dados pessoais recolhidos atrav&eacute;s deste s&iacute;tio (incluindo os obtidos mediante cookies, tecnologias similares, formul&aacute;rios de contacto e outras funcionalidades eventualmente ativas no s&iacute;tio) assenta num ou mais dos seguintes fundamentos jur&iacute;dicos:<\/p>\n<ol style=\"list-style-type: lower-alpha;\" type=\"A\">\n<li><strong>Execu&ccedil;&atilde;o de dilig&ecirc;ncias pr&eacute;-contratuais ou contratuais:<\/strong> quando o tratamento &eacute; necess&aacute;rio para responder a pedidos do utilizador, prestar os servi&ccedil;os solicitados e, quando o s&iacute;tio o preveja, gerir encomendas, contas ou rela&ccedil;&otilde;es contratuais.<\/li>\n<li><strong>Cumprimento de obriga&ccedil;&otilde;es legais:<\/strong> quando o tratamento &eacute; necess&aacute;rio para cumprir obriga&ccedil;&otilde;es fiscais, contabil&iacute;sticas, administrativas, de seguran&ccedil;a ou pedidos das autoridades.<\/li>\n\n<\/ol>\n<p>Um outro fundamento jur&iacute;dico, o <strong>interesse leg&iacute;timo do Respons&aacute;vel pelo tratamento<\/strong>, pode ser utilizado para finalidades espec&iacute;ficas (por ex. garantir a seguran&ccedil;a inform&aacute;tica, prevenir fraudes, defender os direitos do Respons&aacute;vel pelo tratamento em ju&iacute;zo).<\/p>\n\n\n\n\n<p>A n&atilde;o aceita&ccedil;&atilde;o ou a retirada do consentimento pode limitar algumas funcionalidades ou servi&ccedil;os do s&iacute;tio.<\/p>\n\n\n<p><strong>4. Que dados recolhemos quando visita o s&iacute;tio?<\/strong><br> Durante a navega&ccedil;&atilde;o neste s&iacute;tio podem ser recolhidos, tamb&eacute;m atrav&eacute;s de cookies e tecnologias similares como pixel tags, web beacons, local storage e tecnologias equivalentes &ndash; os seguintes dados:<\/p>\n<ul>\n<li>\n<p><strong>Dados de navega&ccedil;&atilde;o e t&eacute;cnicos:<\/strong> informa&ccedil;&otilde;es como endere&ccedil;o IP, identificadores de dispositivo, dados relativos ao sistema operativo e ao navegador, URL solicitados, horas das liga&ccedil;&otilde;es, registos t&eacute;cnicos, prefer&ecirc;ncias t&eacute;cnicas, dados de utiliza&ccedil;&atilde;o recolhidos atrav&eacute;s de cookies e tecnologias de rastreio (pixel tags, web beacons, local storage e ferramentas equivalentes).<\/p>\n<\/li>\n\n\n\n\n\n\n\n<\/ul>\n\n\n<p><strong>5. Como tratamos os seus dados, como os protegemos e durante quanto tempo os conservamos?<\/strong><br> Os dados pessoais recolhidos atrav&eacute;s deste s&iacute;tio s&atilde;o tratados predominantemente com meios eletr&oacute;nicos e digitais segundo os princ&iacute;pios da licitude, lealdade, minimiza&ccedil;&atilde;o dos dados, integridade e confidencialidade.<\/p>\n\n\n<p>Os dados s&atilde;o conservados de acordo com os seguintes prazos:<\/p>\n<ul>\n<li><strong>Prefer&ecirc;ncias e consentimentos de cookies:<\/strong> conservados por 180 dias, conforme a Pol&iacute;tica de Cookies presente neste s&iacute;tio.<\/li>\n<li><strong>Dados de navega&ccedil;&atilde;o e t&eacute;cnicos:<\/strong> conservados pelo tempo estritamente necess&aacute;rio &agrave;s finalidades de seguran&ccedil;a e, em regra, n&atilde;o al&eacute;m de 12 meses, findos os quais s&atilde;o eliminados ou anonimizados, salvo prazos superiores impostos por obriga&ccedil;&otilde;es legais ou pela necessidade de declarar, exercer ou defender um direito em ju&iacute;zo.<\/li>\n<li><strong>Dados associados a eventuais rela&ccedil;&otilde;es contratuais estabelecidas com o Respons&aacute;vel pelo tratamento:<\/strong> quando existam, s&atilde;o conservados durante a vig&ecirc;ncia da rela&ccedil;&atilde;o e, posteriormente, pelo tempo exigido pelas obriga&ccedil;&otilde;es legais aplic&aacute;veis (por exemplo em mat&eacute;ria contabil&iacute;stica e fiscal).<\/li>\n\n<li><strong>Dados introduzidos atrav&eacute;s de formul&aacute;rios ou pedidos espec&iacute;ficos:<\/strong> conservados pelo tempo necess&aacute;rio para dar resposta ao pedido e cumprir a respetiva finalidade, e posteriormente pelo per&iacute;odo eventualmente exigido por obriga&ccedil;&otilde;es legais.<\/li>\n\n<\/ul>\n\n\n<p><strong>6. Quem pode receber os seus dados?<\/strong><br> Podem aceder aos dados pessoais recolhidos atrav&eacute;s deste s&iacute;tio, nos limites das respetivas compet&ecirc;ncias e finalidades:<\/p>\n<ul>\n<li><strong>Pessoas internas autorizadas<\/strong> pelo Respons&aacute;vel pelo tratamento, devidamente instru&iacute;das em mat&eacute;ria de privacidade e seguran&ccedil;a;<\/li>\n<li><strong>Fornecedores e terceiros nomeados Subcontratantes<\/strong> (por exemplo: fornecedores t&eacute;cnicos e servi&ccedil;os inform&aacute;ticos, manuten&ccedil;&atilde;o do s&iacute;tio, fornecedores de correio eletr&oacute;nico, consultores, quando aplic&aacute;vel);<\/li>\n\n<li><strong>Terceiros que fornecem servi&ccedil;os integrados no s&iacute;tio<\/strong> (por ex. tipos de letra, mapas, visualiza&ccedil;&atilde;o de imagens), que podem tratar dados t&eacute;cnicos na qualidade de respons&aacute;veis pelo tratamento aut&oacute;nomos segundo as suas pr&oacute;prias pol&iacute;ticas (consulte, nesse caso, tamb&eacute;m as pol&iacute;ticas de privacidade de tais terceiros);<\/li>\n<li><strong>Autoridades p&uacute;blicas competentes<\/strong> e organismos de controlo, nos limites impostos pela lei ou para satisfazer pedidos da autoridade judici&aacute;ria;<\/li>\n<\/ul>\n<p>A lista atualizada dos destinat&aacute;rios externos pode ser disponibilizada mediante pedido, escrevendo para os contactos do Respons&aacute;vel pelo tratamento.<\/p>\n\n\n<p><strong>7. Para onde podem ser transferidos os seus dados?<\/strong><br> Os dados pessoais recolhidos atrav&eacute;s deste s&iacute;tio podem ser tratados no interior da Uni&atilde;o Europeia \/ Espa&ccedil;o Econ&oacute;mico Europeu. Em alguns casos, a utiliza&ccedil;&atilde;o de servi&ccedil;os de terceiros pode implicar uma transfer&ecirc;ncia para pa&iacute;ses terceiros. No caso de eventuais transfer&ecirc;ncias para os Estados Unidos, estas ocorrem para fornecedores que aderem ao quadro de adequa&ccedil;&atilde;o UE-EUA (Data Privacy Framework) ou, na sua falta, com base em Cl&aacute;usulas Contratuais-Tipo.<\/p>\n\n\n\n\n<p><strong>8. Quais s&atilde;o os seus direitos relativamente aos dados recolhidos?<\/strong><br> O utilizador, nos termos da legisla&ccedil;&atilde;o aplic&aacute;vel, tem o direito de:<\/p>\n<ul>\n<li>Obter a confirma&ccedil;&atilde;o de que os dados pessoais que lhe dizem respeito est&atilde;o ou n&atilde;o a ser tratados e, em caso afirmativo, obter o acesso a esses dados e &agrave;s respetivas informa&ccedil;&otilde;es (direito de acesso).<\/li>\n<li>Solicitar a retifica&ccedil;&atilde;o, a atualiza&ccedil;&atilde;o ou o apagamento dos dados inexatos ou j&aacute; n&atilde;o necess&aacute;rios (direito de retifica&ccedil;&atilde;o e apagamento).<\/li>\n<li>Solicitar a limita&ccedil;&atilde;o ou opor-se ao tratamento dos dados, inclusive para finalidades promocionais\/de defini&ccedil;&atilde;o de perfis, quando previsto.<\/li>\n<li>Solicitar a portabilidade dos dados em formato estruturado e interoper&aacute;vel (quando tecnicamente poss&iacute;vel).<\/li>\n<li>Retirar a qualquer momento o consentimento eventualmente prestado, sem que tal comprometa a licitude do tratamento baseado no consentimento efetuado antes da retirada (por exemplo para o envio de comunica&ccedil;&otilde;es comerciais ou newsletters, quando ativas).<\/li>\n<li class=\"map_any_gdpr_like_text\">Retirar o consentimento prestado para a utiliza&ccedil;&atilde;o de cookies n&atilde;o t&eacute;cnicos e para o tratamento dos dados recolhidos atrav&eacute;s de ferramentas de rastreio.<\/li>\n\n<li>Comunicar eventuais irregularidades ou abusos &agrave;s autoridades de controlo competentes.<\/li>\n<\/ul>\n\n\n\n<p class=\"map_any_gdpr_like_text\">Para exercer tais direitos basta enviar um pedido para os contactos do Respons&aacute;vel pelo tratamento. O Respons&aacute;vel pelo tratamento responder&aacute; sem demora injustificada e, em qualquer caso, no prazo de um m&ecirc;s a contar da rece&ccedil;&atilde;o do pedido, prazo prorrog&aacute;vel por mais dois meses em caso de especial complexidade ou de elevado n&uacute;mero de pedidos, informando desse facto o titular dos dados.<\/p>\n\n\n\n\n<p><strong>9. Como s&atilde;o tratados os dados dos menores?<\/strong><br> A prote&ccedil;&atilde;o dos menores constitui uma prioridade fundamental.<\/p>\n\n<p class=\"map_using_minors_data_off\">Este s&iacute;tio n&atilde;o se dirige diretamente aos menores e n&atilde;o recolhe intencionalmente os seus dados atrav&eacute;s dos seus formul&aacute;rios. Caso, no &acirc;mbito de um pedido ou de uma quest&atilde;o, o utilizador forne&ccedil;a dados pessoais referentes a terceiros &mdash; incluindo eventuais menores &mdash; deve certificar-se de que est&aacute; legitimado para tal; tais dados ser&atilde;o tratados nos limites e para as finalidades do pedido, no respeito pela legisla&ccedil;&atilde;o aplic&aacute;vel. Para pedidos de retifica&ccedil;&atilde;o, limita&ccedil;&atilde;o ou apagamento &eacute; poss&iacute;vel escrever para os contactos do Respons&aacute;vel pelo tratamento.<\/p>\n<p> <\/p>\n<p><strong>10. Como apresentar comunica&ccedil;&otilde;es ou reclama&ccedil;&otilde;es &agrave;s autoridades?<\/strong><br> Se considerar que o tratamento dos seus dados pessoais atrav&eacute;s deste s&iacute;tio n&atilde;o est&aacute; em conformidade com a legisla&ccedil;&atilde;o em vigor, pode apresentar reclama&ccedil;&atilde;o gratuitamente &agrave;s Autoridades de controlo competentes, entre as quais:<\/p>\n<ul>\n<li><a target=\"_blank\" rel=\"nofollow\" href=\"https:\/\/www.edpb.europa.eu\/about-edpb\/our-members_en\">A Autoridade de controlo ou a autoridade de prote&ccedil;&atilde;o de dados pessoais do seu Estado de nacionalidade ou resid&ecirc;ncia;<\/a><\/li>\n\n\n\n\n\n\n\n\n\n\n\n\n\n\n\n\n\n\n\n\n\n\n\n\n\n\n<\/ul>\n\n\n\n<p><strong>11. Como o informamos sobre as altera&ccedil;&otilde;es a esta informa&ccedil;&atilde;o?<\/strong><br> A presente informa&ccedil;&atilde;o est&aacute; sujeita a revis&atilde;o peri&oacute;dica para adapta&ccedil;&atilde;o normativa ou altera&ccedil;&atilde;o dos servi&ccedil;os oferecidos atrav&eacute;s do s&iacute;tio. Qualquer altera&ccedil;&atilde;o significativa ser&aacute; comunicada atrav&eacute;s desta p&aacute;gina.<br> <\/p>\n\n<!--googleon: all-->\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-3286","page","type-page","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Privacy policy - Comec<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.comec-italy.com\/pt-pt\/privacy-policy\/\" \/>\n<meta property=\"og:locale\" content=\"pt_PT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Privacy policy - Comec\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.comec-italy.com\/pt-pt\/privacy-policy\/\" \/>\n<meta property=\"og:site_name\" content=\"Comec\" \/>\n<meta property=\"article:modified_time\" content=\"2024-03-26T08:13:39+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.comec-italy.com\/pt-pt\/privacy-policy\/\",\"url\":\"https:\/\/www.comec-italy.com\/pt-pt\/privacy-policy\/\",\"name\":\"Privacy policy - Comec\",\"isPartOf\":{\"@id\":\"https:\/\/www.comec-italy.com\/pt-pt\/#website\"},\"datePublished\":\"2024-03-25T13:43:04+00:00\",\"dateModified\":\"2024-03-26T08:13:39+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/www.comec-italy.com\/pt-pt\/privacy-policy\/#breadcrumb\"},\"inLanguage\":\"pt-PT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.comec-italy.com\/pt-pt\/privacy-policy\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.comec-italy.com\/pt-pt\/privacy-policy\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.comec-italy.com\/pt-pt\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Privacy policy\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.comec-italy.com\/pt-pt\/#website\",\"url\":\"https:\/\/www.comec-italy.com\/pt-pt\/\",\"name\":\"Comec\",\"description\":\"Idee in movimento\",\"publisher\":{\"@id\":\"https:\/\/www.comec-italy.com\/pt-pt\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.comec-italy.com\/pt-pt\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-PT\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.comec-italy.com\/pt-pt\/#organization\",\"name\":\"Comec\",\"url\":\"https:\/\/www.comec-italy.com\/pt-pt\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-PT\",\"@id\":\"https:\/\/www.comec-italy.com\/pt-pt\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.comec-italy.com\/wp-content\/uploads\/2021\/09\/COMEC_logo.png\",\"contentUrl\":\"https:\/\/www.comec-italy.com\/wp-content\/uploads\/2021\/09\/COMEC_logo.png\",\"width\":350,\"height\":100,\"caption\":\"Comec\"},\"image\":{\"@id\":\"https:\/\/www.comec-italy.com\/pt-pt\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Privacy policy - Comec","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.comec-italy.com\/pt-pt\/privacy-policy\/","og_locale":"pt_PT","og_type":"article","og_title":"Privacy policy - Comec","og_url":"https:\/\/www.comec-italy.com\/pt-pt\/privacy-policy\/","og_site_name":"Comec","article_modified_time":"2024-03-26T08:13:39+00:00","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.comec-italy.com\/pt-pt\/privacy-policy\/","url":"https:\/\/www.comec-italy.com\/pt-pt\/privacy-policy\/","name":"Privacy policy - Comec","isPartOf":{"@id":"https:\/\/www.comec-italy.com\/pt-pt\/#website"},"datePublished":"2024-03-25T13:43:04+00:00","dateModified":"2024-03-26T08:13:39+00:00","breadcrumb":{"@id":"https:\/\/www.comec-italy.com\/pt-pt\/privacy-policy\/#breadcrumb"},"inLanguage":"pt-PT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.comec-italy.com\/pt-pt\/privacy-policy\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.comec-italy.com\/pt-pt\/privacy-policy\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.comec-italy.com\/pt-pt\/"},{"@type":"ListItem","position":2,"name":"Privacy policy"}]},{"@type":"WebSite","@id":"https:\/\/www.comec-italy.com\/pt-pt\/#website","url":"https:\/\/www.comec-italy.com\/pt-pt\/","name":"Comec","description":"Idee in movimento","publisher":{"@id":"https:\/\/www.comec-italy.com\/pt-pt\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.comec-italy.com\/pt-pt\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-PT"},{"@type":"Organization","@id":"https:\/\/www.comec-italy.com\/pt-pt\/#organization","name":"Comec","url":"https:\/\/www.comec-italy.com\/pt-pt\/","logo":{"@type":"ImageObject","inLanguage":"pt-PT","@id":"https:\/\/www.comec-italy.com\/pt-pt\/#\/schema\/logo\/image\/","url":"https:\/\/www.comec-italy.com\/wp-content\/uploads\/2021\/09\/COMEC_logo.png","contentUrl":"https:\/\/www.comec-italy.com\/wp-content\/uploads\/2021\/09\/COMEC_logo.png","width":350,"height":100,"caption":"Comec"},"image":{"@id":"https:\/\/www.comec-italy.com\/pt-pt\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/www.comec-italy.com\/pt-pt\/wp-json\/wp\/v2\/pages\/3286","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.comec-italy.com\/pt-pt\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.comec-italy.com\/pt-pt\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.comec-italy.com\/pt-pt\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.comec-italy.com\/pt-pt\/wp-json\/wp\/v2\/comments?post=3286"}],"version-history":[{"count":3,"href":"https:\/\/www.comec-italy.com\/pt-pt\/wp-json\/wp\/v2\/pages\/3286\/revisions"}],"predecessor-version":[{"id":3289,"href":"https:\/\/www.comec-italy.com\/pt-pt\/wp-json\/wp\/v2\/pages\/3286\/revisions\/3289"}],"wp:attachment":[{"href":"https:\/\/www.comec-italy.com\/pt-pt\/wp-json\/wp\/v2\/media?parent=3286"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}